{"id":16758,"date":"2024-02-09T15:30:13","date_gmt":"2024-02-09T15:30:13","guid":{"rendered":"https:\/\/luxus.wplistingthemes.com\/?page_id=16758"},"modified":"2026-02-05T05:34:34","modified_gmt":"2026-02-05T05:34:34","slug":"home","status":"publish","type":"page","link":"https:\/\/waseelasaeid.com\/ar\/","title":{"rendered":"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16758\" class=\"elementor elementor-16758\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fae855 e-con-full sl-parallax e-flex e-con e-parent\" data-id=\"7fae855\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:20985,&quot;url&quot;:&quot;https:\\\/\\\/waseelasaeid.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/home-hero-bg-1.webp&quot;},{&quot;id&quot;:20986,&quot;url&quot;:&quot;https:\\\/\\\/waseelasaeid.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/home-hero-bg.webp&quot;}],&quot;background_slideshow_slide_duration&quot;:7000,&quot;background_slideshow_slide_transition&quot;:&quot;slide_left&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e146832 e-flex e-con-boxed e-con e-child\" data-id=\"e146832\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9ab166d e-con-full e-flex e-con e-child\" data-id=\"9ab166d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb83f95 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fb83f95\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Waseela<span>  Saeid.<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c24dc31 elementor-widget elementor-widget-text-editor\" data-id=\"c24dc31\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>I help investors and families make structured, data-driven real estate decisions in Dubai, with budgets starting from AED 700,000 up to multi-million dollar portfolios, focusing on risk reduction and return optimization.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a0022 elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-button\" data-id=\"46a0022\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/971566533555\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Consultation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-296cf15 e-con-full e-flex e-con e-child\" data-id=\"296cf15\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f03c04 image-right elementor-widget elementor-widget-image\" data-id=\"4f03c04\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/Untitled-design-2.png\" class=\"attachment-large size-large wp-image-21359\" alt=\"\" srcset=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/Untitled-design-2.png 400w, https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/Untitled-design-2-200x300.png 200w, https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/Untitled-design-2-8x12.png 8w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c81e035 e-flex e-con-boxed e-con e-parent\" data-id=\"c81e035\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0adbad1 e-con-full e-flex e-con e-child\" data-id=\"0adbad1\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-649f353 elementor-widget elementor-widget-video\" data-id=\"649f353\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/videoplayback.mp4\" autoplay=\"\" loop=\"\" controls=\"\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-152f513 e-con-full e-flex e-con e-child\" data-id=\"152f513\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd2dd2b elementor-widget elementor-widget-heading\" data-id=\"cd2dd2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why Waseela Saeid<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94da136 elementor-widget elementor-widget-text-editor\" data-id=\"94da136\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Over 10 years of professional experience<\/li><li>5+ years in Dubai\u2019s real estate market<\/li><li>Specialized in real estate investment &amp; ROI analysis since 2021<\/li><li>Strong background in risk management (insurance)<\/li><li>ROI-driven, not sales-driven decisions<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e8209c e-con-full e-flex e-con e-child\" data-id=\"9e8209c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1620823 e-con-full e-flex e-con e-child\" data-id=\"1620823\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e717f4d elementor-list-item-link-inline elementor-align-start elementor-widget__width-inherit elementor-mobile-align-start elementor-widget elementor-widget-icon-list\" data-id=\"e717f4d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Real Estate Investment Advisory<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Buy, Rent, and Sell Homes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free, Fair &amp; Direct Listing<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d18b592 e-con-full e-flex e-con e-child\" data-id=\"d18b592\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-259e242 elementor-list-item-link-inline elementor-align-start elementor-widget__width-inherit elementor-mobile-align-start elementor-widget elementor-widget-icon-list\" data-id=\"259e242\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ROI &amp; Cash-Flow Analysis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Portfolio Management<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Project &amp; Developer Analysis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b02d478 e-con-full e-flex e-con e-parent\" data-id=\"b02d478\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fc49d2f e-flex e-con-boxed e-con e-child\" data-id=\"fc49d2f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f40da79 e-con-full e-flex e-con e-child\" data-id=\"f40da79\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c454914 elementor-widget elementor-widget-heading\" data-id=\"c454914\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How Can I Help You?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-026d931 elementor-arrows-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"026d931\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;3&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/4.png\" alt=\"4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/2.png\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/6-1.png\" alt=\"6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/7.png\" alt=\"7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/8.png\" alt=\"8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/1-1.png\" alt=\"1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/2-1.png\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/3-1.png\" alt=\"3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/5-1.png\" alt=\"5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b641bbc elementor-widget elementor-widget-text-editor\" data-id=\"b641bbc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>I work closely with Dubai\u2019s top developers to provide early access and strong investment opportunities.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bddc3a e-flex e-con-boxed e-con e-child\" data-id=\"4bddc3a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d1ec2b6 e-con-full e-flex e-con e-child\" data-id=\"d1ec2b6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9defb60 elementor-invisible elementor-widget elementor-widget-luxus-text-image\" data-id=\"9defb60\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"luxus-text-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sl-text-image-container\">\n\t\t\n\t\t\r\n<div class=\"sl-text-image text-image-one\">\r\n\r\n        <div class=\"image-container\"><div class=\"image\" style=\"background-image: url(https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/0a3cad71-6bac-4d63-ba3d-d5b9163ebbcd.jpg);\"><div class=\"img-overlay\" style=\"width:100%; height:100%\"><\/div><\/div><\/div>\r\n    <div class=\"content\">\r\n                \r\n            <div class=\"icon\">\r\n\r\n                <i aria-hidden=\"true\" class=\"sl-icons sl-sale-property\"><\/i>\r\n            <\/div>\r\n                <h2>Sell Property <\/h2>\r\n        <p class=\"text\">I support clients in selling their properties strategically, using market insights and pricing analysis to maximize returns.<\/p>\r\n            <\/div>\r\n<\/div>\n\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44a8ea1 e-con-full e-flex e-con e-child\" data-id=\"44a8ea1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f833c44 elementor-invisible elementor-widget elementor-widget-luxus-text-image\" data-id=\"f833c44\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"luxus-text-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sl-text-image-container\">\n\t\t\n\t\t\r\n<div class=\"sl-text-image text-image-one\">\r\n\r\n        <div class=\"image-container\"><div class=\"image\" style=\"background-image: url(https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/IMG_5343.jpg);\"><div class=\"img-overlay\" style=\"width:100%; height:100%\"><\/div><\/div><\/div>\r\n    <div class=\"content\">\r\n                \r\n            <div class=\"icon\">\r\n\r\n                <i aria-hidden=\"true\" class=\"sl-icons sl-mortgage-o\"><\/i>\r\n            <\/div>\r\n                <h2>Buy Property<\/h2>\r\n        <p class=\"text\">I help investors and families select the right projects through data analysis, market evaluation, and clear ROI projections.<\/p>\r\n            <\/div>\r\n<\/div>\n\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35ea251 e-con-full e-flex e-con e-child\" data-id=\"35ea251\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c40cea elementor-invisible elementor-widget elementor-widget-luxus-text-image\" data-id=\"9c40cea\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"luxus-text-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sl-text-image-container\">\n\t\t\n\t\t\r\n<div class=\"sl-text-image text-image-one\">\r\n\r\n        <div class=\"image-container\"><div class=\"image\" style=\"background-image: url(https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/IMG_6465.jpg);\"><div class=\"img-overlay\" style=\"width:100%; height:100%\"><\/div><\/div><\/div>\r\n    <div class=\"content\">\r\n                \r\n            <div class=\"icon\">\r\n\r\n                <i aria-hidden=\"true\" class=\"sl-icons sl-house-badge\"><\/i>\r\n            <\/div>\r\n                <h2>Rent &amp;Property Management<\/h2>\r\n        <p class=\"text\">management for both local and international investors, ensuring your property stays profitable, well-maintained, and tenant-ready.<\/p>\r\n            <\/div>\r\n<\/div>\n\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17d80dd e-con-full e-flex e-con e-child\" data-id=\"17d80dd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f7ea778 e-con-full e-flex e-con e-child\" data-id=\"f7ea778\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:12249,&quot;url&quot;:&quot;https:\\\/\\\/luxus.wplistingthemes.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/home-hero-bg.webp&quot;},{&quot;id&quot;:7201,&quot;url&quot;:&quot;https:\\\/\\\/luxus.wplistingthemes.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/home-hero-bg-1.webp&quot;}],&quot;background_slideshow_slide_duration&quot;:7000,&quot;background_slideshow_slide_transition&quot;:&quot;slide_left&quot;,&quot;background_slideshow_transition_duration&quot;:1000,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-97f4e20 e-flex e-con-boxed e-con e-child\" data-id=\"97f4e20\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8b92531 e-con-full e-flex e-con e-child\" data-id=\"8b92531\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d912ef8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d912ef8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Find your perfect fit!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff5af15 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ff5af15\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Discover Your <span>Dream<\/span> Home<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ed9b89 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6ed9b89\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>I can find you the perfect property &amp; help you locate the home of your dreams.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73cbe3c e-con-full e-flex e-con e-child\" data-id=\"73cbe3c\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3a34a6 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-child\" data-id=\"b3a34a6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a14fdd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"9a14fdd\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b667ad3 elementor-widget elementor-widget-luxus-info-box\" data-id=\"b667ad3\" data-element_type=\"widget\" data-widget_type=\"luxus-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-info-box-container\">\n\t\t\t\n<div class=\"sl-info-box info-box-one\"> \n    <div class=\"infobox-overlay\"><a href=\"https:\/\/waseelasaeid.com\/contact-us-1\/?v=b6bb43df4525\"><\/a><\/div>    \n        <div class=\"icon\">\n\n            <i aria-hidden=\"true\" class=\"sl-icons sl-apartment\"><\/i>\n        <\/div>\n    \n    <div class=\"content\">\n        <h2 class=\"title\">Apartment<\/h2>\n        <p class=\"text\"><\/p>\n           \n    <\/div>\n<\/div>\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b577e6 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1b577e6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-310e2f3 elementor-widget elementor-widget-luxus-info-box\" data-id=\"310e2f3\" data-element_type=\"widget\" data-widget_type=\"luxus-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-info-box-container\">\n\t\t\t\n<div class=\"sl-info-box info-box-one\"> \n    <div class=\"infobox-overlay\"><a href=\"https:\/\/waseelasaeid.com\/contact-us-1\/?v=b6bb43df4525\"><\/a><\/div>    \n        <div class=\"icon\">\n\n            <i aria-hidden=\"true\" class=\"sl-icons sl-condo\"><\/i>\n        <\/div>\n    \n    <div class=\"content\">\n        <h2 class=\"title\">Office<\/h2>\n        <p class=\"text\"><\/p>\n           \n    <\/div>\n<\/div>\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cc68e4 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"0cc68e4\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33ecea1 elementor-widget elementor-widget-luxus-info-box\" data-id=\"33ecea1\" data-element_type=\"widget\" data-widget_type=\"luxus-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-info-box-container\">\n\t\t\t\n<div class=\"sl-info-box info-box-one\"> \n    <div class=\"infobox-overlay\"><a href=\"https:\/\/waseelasaeid.com\/contact-us-1\/?v=b6bb43df4525\"><\/a><\/div>    \n        <div class=\"icon\">\n\n            <i aria-hidden=\"true\" class=\"sl-icons sl-house\"><\/i>\n        <\/div>\n    \n    <div class=\"content\">\n        <h2 class=\"title\">House<\/h2>\n        <p class=\"text\"><\/p>\n           \n    <\/div>\n<\/div>\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b64d8b1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b64d8b1\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17f80b2 elementor-widget elementor-widget-luxus-info-box\" data-id=\"17f80b2\" data-element_type=\"widget\" data-widget_type=\"luxus-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-info-box-container\">\n\t\t\t\n<div class=\"sl-info-box info-box-one\"> \n    <div class=\"infobox-overlay\"><a href=\"https:\/\/waseelasaeid.com\/contact-us-1\/?v=b6bb43df4525\"><\/a><\/div>    \n        <div class=\"icon\">\n\n            <i aria-hidden=\"true\" class=\"sl-icons sl-villa\"><\/i>\n        <\/div>\n    \n    <div class=\"content\">\n        <h2 class=\"title\">Villa<\/h2>\n        <p class=\"text\"><\/p>\n           \n    <\/div>\n<\/div>\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c9733d e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4c9733d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72f52e5 elementor-widget elementor-widget-luxus-info-box\" data-id=\"72f52e5\" data-element_type=\"widget\" data-widget_type=\"luxus-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-info-box-container\">\n\t\t\t\n<div class=\"sl-info-box info-box-one\"> \n    <div class=\"infobox-overlay\"><a href=\"https:\/\/waseelasaeid.com\/contact-us-1\/?v=b6bb43df4525\"><\/a><\/div>    \n        <div class=\"icon\">\n\n            <i aria-hidden=\"true\" class=\"sl-icons sl-shop\"><\/i>\n        <\/div>\n    \n    <div class=\"content\">\n        <h2 class=\"title\">Shop<\/h2>\n        <p class=\"text\"><\/p>\n           \n    <\/div>\n<\/div>\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0da3d66 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"0da3d66\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5fd75b elementor-widget elementor-widget-luxus-info-box\" data-id=\"a5fd75b\" data-element_type=\"widget\" data-widget_type=\"luxus-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-info-box-container\">\n\t\t\t\n<div class=\"sl-info-box info-box-one\"> \n    <div class=\"infobox-overlay\"><a href=\"https:\/\/waseelasaeid.com\/contact-us-1\/?v=b6bb43df4525\"><\/a><\/div>    \n        <div class=\"icon\">\n\n            <i aria-hidden=\"true\" class=\"sl-icons sl-office\"><\/i>\n        <\/div>\n    \n    <div class=\"content\">\n        <h2 class=\"title\">Management<\/h2>\n        <p class=\"text\"><\/p>\n           \n    <\/div>\n<\/div>\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f63e0ab e-flex e-con-boxed e-con e-child\" data-id=\"f63e0ab\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8465ada elementor-widget elementor-widget-luxus-scroll-down\" data-id=\"8465ada\" data-element_type=\"widget\" data-widget_type=\"luxus-scroll-down.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-scroll-down-container\">\n\t\t\t\t<a href=\"#feature-properties\" class=\"sl-scroll-down\">\n\t\t\t\t\t<div class=\"mouse_scroll\">\n\t\t\t\t\t\t<div class=\"sl-mouse\">\n\t\t\t\t\t\t\t<div class=\"sl-wheel\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<span class=\"sl_scroll_arrows one\"><\/span>\n\t\t\t\t\t\t\t<span class=\"sl_scroll_arrows two\"><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8197ea5 e-con-full e-flex e-con e-parent\" data-id=\"8197ea5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7df6810 e-flex e-con-boxed e-con e-child\" data-id=\"7df6810\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6ef21ad e-con-full e-flex e-con e-child\" data-id=\"6ef21ad\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f6f2c3 e-con-full e-flex e-con e-child\" data-id=\"0f6f2c3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f40939 elementor-widget elementor-widget-heading\" data-id=\"8f40939\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Be the first to explore the latest off-plan launches\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1605826 elementor-widget elementor-widget-text-editor\" data-id=\"1605826\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong data-start=\"2043\" data-end=\"2100\">Dubai\u2019s real estate market continues to break records<\/strong>, with sales volumes hitting historic highs and strong activity across primary and secondary markets \u2014 a bullish backdrop for both investors and homeowners.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f98430c e-con-full e-flex e-con e-child\" data-id=\"f98430c\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fbf5f2 e-flex e-con-boxed e-con e-child\" data-id=\"7fbf5f2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a246ed e-con-full e-flex e-con e-child\" data-id=\"6a246ed\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82f5652 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-luxus-property_category\" data-id=\"82f5652\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"luxus-property_category.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-category-container\">\n\t\t\t\n\t\t\t<div class=\"sl-category sl-cat\"><img decoding=\"async\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/2-3.png\" class=\"cat-image\" alt=\"\"><\/div>\r\n\r\n\r\n\n\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-222e299 elementor-widget elementor-widget-heading\" data-id=\"222e299\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hado<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84dba64 elementor-widget elementor-widget-text-editor\" data-id=\"84dba64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hado by Beyond is a contemporary residential development offering refined living spaces, curated lifestyle amenities, and strong long-term investment potential within a well-connected.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18f0a57 e-con-full e-flex e-con e-child\" data-id=\"18f0a57\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c01530 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-luxus-property_category\" data-id=\"1c01530\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"luxus-property_category.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-category-container\">\n\t\t\t\n\t\t\t<div class=\"sl-category sl-cat\"><img decoding=\"async\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/1-3.png\" class=\"cat-image\" alt=\"\"><\/div>\r\n\r\n\r\n\n\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af41f95 elementor-widget elementor-widget-heading\" data-id=\"af41f95\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mareva 1 &amp; 2 the Oasis<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e24e28a elementor-widget elementor-widget-text-editor\" data-id=\"e24e28a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A premium collection of 4- to 6-bedroom standalone villas set around tranquil lagoons and lush landscapes, offering spacious layouts, privacy, and resort-inspired living .<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35b6f6f e-con-full e-flex e-con e-child\" data-id=\"35b6f6f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-402b192 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-luxus-property_category\" data-id=\"402b192\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"luxus-property_category.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"sl-category-container\">\n\t\t\t\n\t\t\t<div class=\"sl-category sl-cat\"><img decoding=\"async\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/3-3.png\" class=\"cat-image\" alt=\"\"><\/div>\r\n\r\n\r\n\n\t\t\t<\/div>\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa929b1 elementor-widget elementor-widget-heading\" data-id=\"fa929b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">The Symphony<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95123a5 elementor-widget elementor-widget-text-editor\" data-id=\"95123a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Imtiaz Symphony Tower is a premium high-rise development offering elegant residences, modern amenities, and a lifestyle designed for comfort and convenience.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5e7dcb e-con-full sl-parallax e-flex e-con e-parent\" data-id=\"c5e7dcb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-aa797e9 e-con-full e-flex e-con e-child\" data-id=\"aa797e9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1d983ce e-flex e-con-boxed e-con e-child\" data-id=\"1d983ce\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a0da95b e-con-full e-flex e-con e-child\" data-id=\"a0da95b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4be526 elementor-widget elementor-widget-heading\" data-id=\"f4be526\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Looking to Buy a New Property or Sell an Existing One?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4355050 elementor-hidden-mobile elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"4355050\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/971566533555\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Speak With Me<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14e1099f e-flex e-con-boxed e-con e-parent\" data-id=\"14e1099f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-250558a e-con-full e-flex e-con e-child\" data-id=\"250558a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-43d2f79 e-con-full e-flex e-con e-child\" data-id=\"43d2f79\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0d7500d e-con-full e-flex e-con e-child\" data-id=\"0d7500d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01dfba9 elementor-widget elementor-widget-heading\" data-id=\"01dfba9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get in touch<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fd5b65 e-con-full e-flex e-con e-child\" data-id=\"1fd5b65\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fff8b3a elementor-widget elementor-widget-text-editor\" data-id=\"fff8b3a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em data-start=\"253\" data-end=\"361\">Feel free to reach out to discuss projects, partnerships, or investment opportunities, or to ask any questions.<\/em><\/p><p data-start=\"363\" data-end=\"374\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fffd0d elementor-widget elementor-widget-heading\" data-id=\"8fffd0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Contact Information<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96c57bc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"96c57bc\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sl-icons sl-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">00971566533555<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sl-icons sl-email-t\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@waseelasaeid.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"sl-icons sl-location-o\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dubai, united arab emirates<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e29467f elementor-widget elementor-widget-heading\" data-id=\"e29467f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Follow Us<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-225500a elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"225500a\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-458faf3\" href=\"https:\/\/www.facebook.com\/waseela.saeid?mibextid=wwXIfr&#038;rdid=HW5taH3NKgYta3yh&#038;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F16HZbA37Gg%2F%3Fmibextid%3DwwXIfr#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-e04d019\" href=\"https:\/\/www.instagram.com\/waseelasaeid\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-c1f5f20\" href=\"https:\/\/x.com\/waseela5665\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-4890532\" href=\"https:\/\/www.facebook.com\/waseela.saeid?mibextid=wwXIfr&#038;rdid=HW5taH3NKgYta3yh&#038;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F16HZbA37Gg%2F%3Fmibextid%3DwwXIfr#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-snapchat elementor-repeater-item-4b5df56\" href=\"https:\/\/www.snapchat.com\/@waseelasaeid?invite_id=wF4mUDse&#038;locale=en_AE&#038;share_id=mdUY9XZgT2W8G4bDg8zAdw&#038;sid=269974793162400e97281caed5913c6c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Snapchat<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-snapchat\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm169.5 338.9c-3.5 8.1-18.1 14-44.8 18.2-1.4 1.9-2.5 9.8-4.3 15.9-1.1 3.7-3.7 5.9-8.1 5.9h-.2c-6.2 0-12.8-2.9-25.8-2.9-17.6 0-23.7 4-37.4 13.7-14.5 10.3-28.4 19.1-49.2 18.2-21 1.6-38.6-11.2-48.5-18.2-13.8-9.7-19.8-13.7-37.4-13.7-12.5 0-20.4 3.1-25.8 3.1-5.4 0-7.5-3.3-8.3-6-1.8-6.1-2.9-14.1-4.3-16-13.8-2.1-44.8-7.5-45.5-21.4-.2-3.6 2.3-6.8 5.9-7.4 46.3-7.6 67.1-55.1 68-57.1 0-.1.1-.2.2-.3 2.5-5 3-9.2 1.6-12.5-3.4-7.9-17.9-10.7-24-13.2-15.8-6.2-18-13.4-17-18.3 1.6-8.5 14.4-13.8 21.9-10.3 5.9 2.8 11.2 4.2 15.7 4.2 3.3 0 5.5-.8 6.6-1.4-1.4-23.9-4.7-58 3.8-77.1C183.1 100 230.7 96 244.7 96c.6 0 6.1-.1 6.7-.1 34.7 0 68 17.8 84.3 54.3 8.5 19.1 5.2 53.1 3.8 77.1 1.1.6 2.9 1.3 5.7 1.4 4.3-.2 9.2-1.6 14.7-4.2 4-1.9 9.6-1.6 13.6 0 6.3 2.3 10.3 6.8 10.4 11.9.1 6.5-5.7 12.1-17.2 16.6-1.4.6-3.1 1.1-4.9 1.7-6.5 2.1-16.4 5.2-19 11.5-1.4 3.3-.8 7.5 1.6 12.5.1.1.1.2.2.3.9 2 21.7 49.5 68 57.1 4 1 7.1 5.5 4.9 10.8z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-567e4d2 e-con-full e-flex e-con e-child\" data-id=\"567e4d2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0069b2e e-con-full e-flex e-con e-child\" data-id=\"0069b2e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-650dde6 elementor-widget elementor-widget-heading\" data-id=\"650dde6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact me<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caa2a35 elementor-widget elementor-widget-text-editor\" data-id=\"caa2a35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Feel free to contact with us.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8da77e4 e-con-full e-flex e-con e-child\" data-id=\"8da77e4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e59561 elementor-widget elementor-widget-shortcode\" data-id=\"4e59561\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f20559-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"20559\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/16758#wpcf7-f20559-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"20559\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f20559-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"container\">\n\t<div class=\"row gx-3\">\n\t\t<div class=\"col-md-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"full-name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full Name\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" id=\"email-address\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email Address\" value=\"\" type=\"email\" name=\"email-address\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"mobile-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"mobile-number\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mobile Number\" value=\"\" type=\"text\" name=\"mobile-number\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"service\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"cfs-dropdown\" aria-required=\"true\" aria-invalid=\"false\" name=\"service\"><option value=\"\">Select Service<\/option><option value=\"Mortgage\">Mortgage<\/option><option value=\"Development\">Development<\/option><option value=\"Property Management\">Property Management<\/option><option value=\"Property Sales\">Property Sales<\/option><option value=\"Other\">Other<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<div class=\"form-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" placeholder=\"Enter Your Message\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div>\n\t\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner sl-btn-fill\" type=\"submit\" value=\"Send Message\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fa04c4 e-con-full e-flex e-con e-parent\" data-id=\"9fa04c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5bb37c5 e-flex e-con-boxed e-con e-child\" data-id=\"5bb37c5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d1593d e-con-full e-flex e-con e-child\" data-id=\"3d1593d\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8863a9d e-con-full e-flex e-con e-child\" data-id=\"8863a9d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed63c51 elementor-widget elementor-widget-heading\" data-id=\"ed63c51\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clients Feedback<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9e46ce elementor-widget elementor-widget-text-editor\" data-id=\"c9e46ce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong data-start=\"9\" data-end=\"84\">testimonials<\/strong>\u00a0tailored to your positioning as a Real Estate Investment\u00a0Advisor &amp; ROI Analyst in Dubai.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643c5b4 elementor-widget elementor-widget-shortcode\" data-id=\"643c5b4\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wp-gr rpi wpac\" data-id=\"21498\" data-layout=\"slider\" data-exec=\"false\" data-options='{&quot;text_size&quot;:&quot;&quot;,&quot;trans&quot;:{&quot;read more&quot;:&quot;\\u0627\\u0642\\u0631\\u0623 \\u0627\\u0644\\u0645\\u0632\\u064a\\u062f&quot;}}'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"display:none!important\"><symbol id=\"grw-tripadvisor\" viewBox=\"0 0 713.496 713.496\"><g><circle fill=\"#34E0A1\" cx=\"356.749\" cy=\"356.748\" r=\"356.748\"\/><path d=\"M577.095,287.152l43.049-46.836h-95.465c-47.792-32.646-105.51-51.659-167.931-51.659   c-62.342,0-119.899,19.054-167.612,51.659H93.432l43.049,46.836c-26.387,24.075-42.929,58.754-42.929,97.259   c0,72.665,58.914,131.578,131.579,131.578c34.519,0,65.968-13.313,89.446-35.077l42.172,45.919l42.172-45.879   c23.478,21.764,54.887,35.037,89.406,35.037c72.665,0,131.658-58.913,131.658-131.578   C620.024,345.866,603.483,311.188,577.095,287.152z M225.17,473.458c-49.188,0-89.047-39.859-89.047-89.047   s39.86-89.048,89.047-89.048c49.187,0,89.047,39.86,89.047,89.048S274.357,473.458,225.17,473.458z M356.788,381.82   c0-58.595-42.61-108.898-98.853-130.383c30.413-12.716,63.776-19.771,98.813-19.771s68.439,7.055,98.853,19.771   C399.399,272.962,356.788,323.226,356.788,381.82z M488.367,473.458c-49.188,0-89.048-39.859-89.048-89.047   s39.86-89.048,89.048-89.048s89.047,39.86,89.047,89.048S537.554,473.458,488.367,473.458z M488.367,337.694   c-25.79,0-46.677,20.887-46.677,46.677c0,25.789,20.887,46.676,46.677,46.676c25.789,0,46.676-20.887,46.676-46.676   C535.042,358.621,514.156,337.694,488.367,337.694z M271.846,384.411c0,25.789-20.887,46.676-46.676,46.676   s-46.676-20.887-46.676-46.676c0-25.79,20.887-46.677,46.676-46.677C250.959,337.694,271.846,358.621,271.846,384.411z\"\/><\/g><\/symbol><symbol id=\"grw-google\" viewBox=\"0 0 512 512\"><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M482.56 261.36c0-16.73-1.5-32.83-4.29-48.27H256v91.29h127.01c-5.47 29.5-22.1 54.49-47.09 71.23v59.21h76.27c44.63-41.09 70.37-101.59 70.37-173.46z\" fill=\"#4285f4\"\/><path d=\"M256 492c63.72 0 117.14-21.13 156.19-57.18l-76.27-59.21c-21.13 14.16-48.17 22.53-79.92 22.53-61.47 0-113.49-41.51-132.05-97.3H45.1v61.15c38.83 77.13 118.64 130.01 210.9 130.01z\" fill=\"#34a853\"\/><path d=\"M123.95 300.84c-4.72-14.16-7.4-29.29-7.4-44.84s2.68-30.68 7.4-44.84V150.01H45.1C29.12 181.87 20 217.92 20 256c0 38.08 9.12 74.13 25.1 105.99l78.85-61.15z\" fill=\"#fbbc05\"\/><path d=\"M256 113.86c34.65 0 65.76 11.91 90.22 35.29l67.69-67.69C373.03 43.39 319.61 20 256 20c-92.25 0-172.07 52.89-210.9 130.01l78.85 61.15c18.56-55.78 70.59-97.3 132.05-97.3z\" fill=\"#ea4335\"\/><path d=\"M20 20h472v472H20V20z\"\/><\/g><\/symbol><\/svg><div class=\"grw-row grw-row-m\" data-options='{\"speed\":3,\"autoplay\":true,\"mousestop\":true,\"breakpoints\":\"\"}'><div class=\"grw-header\"><div class=\"grw-header-inner rpi-flx rpi-row12\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/lh3.googleusercontent.com\/places\/ANXAkqFHbMgf9U6237C2kc54AT_1Pab7JszsrihR3nAML6dVfXjuRqI7tnFST6DhSqlNt1tHKmXqHNGEFSzehDx7Mo9Dsn8dVjcD0w=s4800-w300-h300\" loading=\"lazy\" alt=\"Waseela saeid place picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7')this.src='data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7';\" ><\/div><div class=\"rpi-flx rpi-col8\"><div class=\"wp-google-name\"><a href=\"https:\/\/maps.google.com\/?cid=9780239422014714538&#038;g_mp=CiVnb29nbGUubWFwcy5wbGFjZXMudjEuUGxhY2VzLkdldFBsYWNlEAIYBCAA\" target=\"_blank\" rel=\"nofollow noopener\">Waseela saeid<\/a><\/div><span class=\"rpi-stars\" style=\"--rating:5.0\">5.0<\/span><div class=\"wp-google-based\">\u0627\u0633\u062a\u0646\u0627\u062f\u0627\u064b \u0625\u0644\u0649 7 \u062a\u0642\u064a\u064a\u0645\u0627\u064b<\/div><div class=\"wp-google-powered\">powered by <span><span style=\"color:#3c6df0!important\">G<\/span><span style=\"color:#d93025!important\">o<\/span><span style=\"color:#fb8e28!important\">o<\/span><span style=\"color:#3c6df0!important\">g<\/span><span style=\"color:#188038!important\">l<\/span><span style=\"color:#d93025!important\">e<\/span><\/span><\/div><div class=\"wp-google-wr\"><a href=\"https:\/\/search.google.com\/local\/writereview?placeid=ChIJuynx3HI7qWMRqnJ1t-9juoc\" target=\"_blank\" rel=\"nofollow noopener\" onclick=\"return rplg_leave_review_window.call(this)\">\u0642\u0645 \u0628\u062a\u0642\u064a\u064a\u0645\u0646\u0627 \u0639\u0644\u0649<svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"><\/use><\/svg><\/a><\/div><\/div><\/div><\/div><div class=\"rpi-slides-root grw-content\"><div class=\"grw-content-inner\"><button class=\"rpi-ltgt rpi-lt grw-prev\" tabindex=\"0\"><\/button><div class=\"rpi-slides grw-reviews rpi-slides-bite\" data-count=\"5\" data-offset=\"5\"><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/ChIJuynx3HI7qWMRqnJ1t-9juoc_8c8860f44c2e2cde30d7f6aec70a8d9e.jpg\" loading=\"lazy\" alt=\"Dory El Tannoury profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/112434981721483000491\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Dory El Tannoury<\/a><div class=\"wp-google-time\" data-time=\"1768480038\">12:27 15 Jan 26<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Waseela always tailor his offering according to your needs and he is always supportive replying on time and following up on all matters<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/ChIJuynx3HI7qWMRqnJ1t-9juoc_64a608fdfeeb8221b12a5342678c3ca2.jpg\" loading=\"lazy\" alt=\"Tugba Al saadi profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/113930586774622923677\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Tugba Al saadi<\/a><div class=\"wp-google-time\" data-time=\"1768128874\">10:54 11 Jan 26<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Hello dear Al Waseela<br \/><br \/>I want to express my great thanks to him for his efforts and following up for renting and selling properties in very professional way and for sure very quickly. Also he is responding calls and messages at any time which is very important for clients.<br \/><br \/>Thanks to him<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/ChIJuynx3HI7qWMRqnJ1t-9juoc_f21ed6bb9a7d9026398a8c079bec1aed.jpg\" loading=\"lazy\" alt=\"Adil Saeed profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/112492052408597270547\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Adil Saeed<\/a><div class=\"wp-google-time\" data-time=\"1767958077\">11:27 09 Jan 26<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Dear Brother Al-Wasila,<br \/>Greetings to you, and best wishes to you and your family.<br \/>We attest to your integrity, professionalism, and attention to detail in your real estate dealings, both large and small, which instills confidence in everyone who has purchased property from you. These are precisely the qualities every property buyer seeks.<br \/><br \/>I wish you continued success and prosperity in this field, and I hope you maintain this same approach in dealing with your clients in the future, God willing.<br \/><br \/>Your brother, Dr. Adel Mohammed Ahmed Saeed, Dammam, Saudi Arabia<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/ChIJuynx3HI7qWMRqnJ1t-9juoc_91ac586fdcf45a8b178f0571f08ef228.jpg\" loading=\"lazy\" alt=\"Mahdi Balla profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/108324419732132298705\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Mahdi Balla<\/a><div class=\"wp-google-time\" data-time=\"1767883987\">14:53 08 Jan 26<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">I know waseela for 3 years now , All I can say about him in words :<br \/>Hard worker- Smart- Confident- Honest -Win\/Win Mentality<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/ChIJuynx3HI7qWMRqnJ1t-9juoc_3ab2ad5238904966939952161abb36ec.jpg\" loading=\"lazy\" alt=\"Mohallab Hamdan profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/waseelasaeid.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/107279525299464555389\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Mohallab Hamdan<\/a><div class=\"wp-google-time\" data-time=\"1767880819\">14:00 08 Jan 26<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">My testimony regarding Al Wasila, a real estate consultant, is biased; the man is trustworthy and dearer than a friend or brother.<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><\/div><button class=\"rpi-ltgt rpi-gt grw-next\" tabindex=\"0\"><\/button><div class=\"rpi-dots-wrap\"><div class=\"rpi-dots\"><\/div><\/div><\/div><\/div><\/div><script>(function(p){if(!p)return;let w=p.offsetWidth,m=function(a,b){return Math.min(a,b)===a};p.querySelector('.grw-row').classList.replace('grw-row-m','grw-row-'+(m(w,510)?'xs':m(w,750)?'x':m(w,1100)?'s':m(w,1450)?'m':m(w,1800)?'l':'xl'))})(document.currentScript?.parentElement)<\/script><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6131cac e-con-full e-flex e-con e-parent\" data-id=\"6131cac\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b341a6d e-flex e-con-boxed e-con e-child\" data-id=\"b341a6d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d1fca6d e-con-full e-flex e-con e-child\" data-id=\"d1fca6d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4ac71e elementor-widget elementor-widget-heading\" data-id=\"d4ac71e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90ad438 e-con-full e-flex e-con e-child\" data-id=\"90ad438\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb84b1a e-flex e-con-boxed e-con e-child\" data-id=\"bb84b1a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b48e0 elementor-arrows-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"d0b48e0\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;3&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/4.png\" alt=\"4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/2.png\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/6-1.png\" alt=\"6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/7.png\" alt=\"7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/8.png\" alt=\"8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/1-1.png\" alt=\"1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/2-1.png\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/3-1.png\" alt=\"3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/waseelasaeid.com\/wp-content\/uploads\/2025\/12\/5-1.png\" alt=\"5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Waseela Saeid. I help investors and families make structured, data-driven real estate decisions in Dubai, with budgets starting from AED 700,000 up to multi-million dollar portfolios, focusing on risk reduction and return optimization. Book Consultation https:\/\/waseelasaeid.com\/wp-content\/uploads\/2026\/01\/videoplayback.mp4 Why Waseela Saeid Over 10 years of professional experience 5+ years in Dubai\u2019s real estate market Specialized in real [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-16758","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/pages\/16758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/comments?post=16758"}],"version-history":[{"count":20,"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/pages\/16758\/revisions"}],"predecessor-version":[{"id":21515,"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/pages\/16758\/revisions\/21515"}],"wp:attachment":[{"href":"https:\/\/waseelasaeid.com\/ar\/wp-json\/wp\/v2\/media?parent=16758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}